{"id":4548,"date":"2016-03-06T12:05:41","date_gmt":"2016-03-06T11:05:41","guid":{"rendered":"http:\/\/www.die-erfolgs-strategie.de\/aktien\/?p=4548"},"modified":"2016-03-08T17:25:03","modified_gmt":"2016-03-08T16:25:03","slug":"sell-gmbh","status":"publish","type":"post","link":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/weltmarktfuehrer\/sell-gmbh\/","title":{"rendered":"Sell GmbH"},"content":{"rendered":"<p>Die <b>Sell GmbH<\/b>, ein Tochterunternehmen der franz\u00f6sischen Zodiac Aerospace Gruppe, ist ein Flugzeugzulieferer von Flugzeugk\u00fcchen (<i>Galley<\/i>) und Flugzeugk\u00fcchenger\u00e4ten (<i>Galley Inserts<\/i>).<\/p>\n<table>\n<tbody>\n<tr bgcolor=\"#e6e6fa\">\n<td><strong>Weltmarktf\u00fchrer<\/strong><\/td>\n<td><strong>Rang 491<\/strong><\/td>\n<td>Stand 2015<\/td>\n<td>Zur\u00fcck zur Liste: <a href=\"http:\/\/www.die-erfolgs-strategie.de\/aktien\/listen\/deutschlands-weltmarktfuehrer\/deutschlands-weltmarktfuehrer-rang-401-bis-500\/\">Weltmarktf\u00fchrer Rang 401 \u2013 500<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Das Unternehmen hat seinen Hauptsitz in Herborn, sowie eine Produktionsst\u00e4tte in Burg und ein Sell-eigenes Konstruktionsb\u00fcro in Homberg (Ohm). Insgesamt besch\u00e4ftigt Sell 1600 Mitarbeiter.<\/p>\n<p>Die Sell GmbH produziert Flugzeugk\u00fcchen und Flugzeugeinrichtungen f\u00fcr weltweit f\u00fchrende Fluggesellschaften und Flugzeughersteller.<\/p>\n<p>2011 hat Sell den 30.000. Konfektionsofen der -8201 Serie an die Deutsche Lufthansa ausgeliefert. Im Jahr 2015 konnte Sell mit der 50.000 Flugzeugk\u00fcche f\u00fcr einen A380 von Etihad Airways ein weiteres Jubil\u00e4um feiern.<\/p>\n<p>Sell besitzt 70 Prozent Marktanteil bei der Flugzeugk\u00fcchenausstattung des neuen Airbus Gro\u00dfraumfliegers A380 und ist Weltmarktf\u00fchrer im Bereich der Langstreckenflugzeuge. Neben den Flugzeugk\u00fcchen und \u00d6fen geh\u00f6ren auch Kaffeemaschinen, Wasserkocher, Br\u00f6tchenw\u00e4rmer und andere Elemente der Kabineneinrichtung zum Portfolio der Firma.<\/p>\n<h3>Historische Daten zur Sell GmbH<\/h3>\n<table>\n<tbody>\n<tr bgcolor=\"#ffd6a0\">\n<td style=\"border-bottom: 2px solid #000; border-right: 1px solid #000;\"><strong>Jahr<\/strong><\/td>\n<td style=\"border-bottom: 2px solid #000;\"><\/td>\n<\/tr>\n<tr>\n<td><strong>1946<\/strong><\/td>\n<td>Die Burger Eisenwerke stellten Werner Sell ein, der mit seiner Firma auch Flugzeugk\u00fcchen produzierte.<\/td>\n<\/tr>\n<tr>\n<td><strong>1958<\/strong><\/td>\n<td>wurde die Burger Eisenwerke von der Buderus AG \u00fcbernommen und ein Teilbereich als \u201eBuderus Sell GmbH\u201c gef\u00fchrt<\/td>\n<\/tr>\n<tr>\n<td><strong>1990<\/strong><\/td>\n<td>wurde eine neue Werkshalle in Ludwigsh\u00fctte in Betrieb genommen<\/td>\n<\/tr>\n<tr>\n<td><strong>1997<\/strong><\/td>\n<td>wurde die Buderus Sell GmbH durch die englische Firma <em>Britax International<\/em> \u00fcbernommen<\/td>\n<\/tr>\n<tr>\n<td><strong>2003<\/strong><\/td>\n<td>wurde zu Ehren des Ingenieurs Werner Sell die Unternehmensteile von Britax in \u201eSell GmbH\u201c umbenannt.<\/td>\n<\/tr>\n<tr>\n<td><strong>2010<\/strong><\/td>\n<td>ver\u00e4u\u00dferte Britax das Unternehmen an den franz\u00f6sischen Konzern Zodiac Group<\/td>\n<\/tr>\n<tr>\n<td><strong>\u00a0<\/strong><\/td>\n<td>Mit 25.200 Mitarbeitern ist Zodiac Aerospace das weltweit f\u00fchrende Unternehmen in der Flugzeugzulieferindustrie. Sell ist neben anderen Tochterunternehmen einer der 117 Standorte weltweit.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Quellenangabe:<\/h3>\n<table>\n<tbody>\n<tr bgcolor=\"#ffd6a0\">\n<td style=\"border-bottom: 2px solid #000; border-right: 1px solid #000;\"><strong>Unternehmen<\/strong><\/td>\n<td style=\"border-bottom: 2px solid #000;\"><\/td>\n<\/tr>\n<tr>\n<td><strong>Beschreibung<\/strong><\/td>\n<td>\u00a0https:\/\/de.wikipedia.org\/wiki\/Sell_GmbH<\/td>\n<\/tr>\n<tr>\n<td><strong>Historie<\/strong><\/td>\n<td>\u00a0https:\/\/de.wikipedia.org\/wiki\/Sell_GmbH<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Die Sell GmbH, ein Tochterunternehmen der franz\u00f6sischen Zodiac Aerospace Gruppe, ist ein Flugzeugzulieferer von Flugzeugk\u00fcchen (Galley) und Flugzeugk\u00fcchenger\u00e4ten (Galley Inserts). Weltmarktf\u00fchrer Rang 491 Stand 2015 Zur\u00fcck zur Liste: Weltmarktf\u00fchrer Rang 401 \u2013 500 &nbsp; Das Unternehmen hat seinen Hauptsitz in Herborn, sowie eine Produktionsst\u00e4tte in Burg und ein Sell-eigenes Konstruktionsb\u00fcro in Homberg (Ohm). Insgesamt besch\u00e4ftigt [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,30],"tags":[155,154,110,557],"class_list":["post-4548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-boersennotiert","category-weltmarktfuehrer","tag-geschichte","tag-historie","tag-meilensteine","tag-sell-gmbh"],"_links":{"self":[{"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/posts\/4548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/comments?post=4548"}],"version-history":[{"count":6,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/posts\/4548\/revisions"}],"predecessor-version":[{"id":4675,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/posts\/4548\/revisions\/4675"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/media\/4613"}],"wp:attachment":[{"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/media?parent=4548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/categories?post=4548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/tags?post=4548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}