{"id":4538,"date":"2016-03-06T12:03:41","date_gmt":"2016-03-06T11:03:41","guid":{"rendered":"http:\/\/www.die-erfolgs-strategie.de\/aktien\/?p=4538"},"modified":"2016-03-08T11:59:12","modified_gmt":"2016-03-08T10:59:12","slug":"baumueller-nuernberg-gmbh","status":"publish","type":"post","link":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/weltmarktfuehrer\/baumueller-nuernberg-gmbh\/","title":{"rendered":"Baum\u00fcller N\u00fcrnberg GmbH"},"content":{"rendered":"<p><b>Baum\u00fcller<\/b> ist einer der weltweit f\u00fchrenden Hersteller von elektrischen Automatisierungs- und Antriebssystemen.<\/p>\n<table>\n<tbody>\n<tr bgcolor=\"#e6e6fa\">\n<td><strong>Weltmarktf\u00fchrer<\/strong><\/td>\n<td><strong>Rang 486<\/strong><\/td>\n<td>Stand 2015<\/td>\n<td>Zur\u00fcck zur Liste: <a href=\"http:\/\/www.die-erfolgs-strategie.de\/aktien\/listen\/deutschlands-weltmarktfuehrer\/deutschlands-weltmarktfuehrer-rang-401-bis-500\/\">Weltmarktf\u00fchrer Rang 401 \u2013 500<\/a><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Das Unternehmen wurde 1930 gegr\u00fcndet und befindet sich nach wie vor in Familienbesitz. Der Stammsitz ist in <a title=\"N\u00fcrnberg\" href=\"https:\/\/de.wikipedia.org\/wiki\/N%C3%BCrnberg\" target=\"_blank\" rel=\"noopener\">N\u00fcrnberg<\/a>. Heute ist die Baum\u00fcller Gruppe an \u00fcber 42 Standorten weltweit vertreten.<\/p>\n<p><strong>Das Unternehmen besteht aus vier Teilbereichen:<\/strong><\/p>\n<ul>\n<li>Komponenten\/Systeme: Zu diesem Unternehmensbereich z\u00e4hlen Systeme, Kleinsysteme, Steuerungen und Applikationen.<\/li>\n<li>Engineering\/Systeme: Zu Engineering\/Systeme geh\u00f6ren Automatisierung, Engineering, Schaltschr\u00e4nke, Blechl\u00f6sungen und Applikationen.<\/li>\n<li>Dienstleistungen: Im Bereich Dienstleistungen befinden sich die Service-Leistungen Beratung, Reparatur, Ersatzteile und Tauschger\u00e4te.<\/li>\n<li>Vertrieb: Der Vertrieb ist in Inland und Export aufgeteilt.<\/li>\n<\/ul>\n<p><strong>Das Unternehmen entwickelt und produziert<\/strong><\/p>\n<ul>\n<li>Elektromotoren<\/li>\n<li>Umrichter<\/li>\n<li>Steuerungs- und Regelungstechnik<\/li>\n<li>Netzwerke in der Industriekommunikation<\/li>\n<li>Schaltschr\u00e4nke, -s\u00e4ulen, -felder und -pulte<\/li>\n<li>Blechteile und -verkleidungen<\/li>\n<li>Kabelkonfektion<\/li>\n<li>Energieeffiziente Antriebssysteme<\/li>\n<\/ul>\n<p>Mit diesen Komponenten plant und fertigt der Hersteller Antriebs- und Automatisierungssysteme, die in allen Branchen des Maschinenbaus f\u00fcr die Automatisierung eingesetzt werden.<\/p>\n<h3>Historische Daten zur Baum\u00fcller N\u00fcrnberg GmbH<\/h3>\n<table>\n<tbody>\n<tr bgcolor=\"#ffd6a0\">\n<td style=\"border-bottom: 2px solid #000; border-right: 1px solid #000;\"><strong>Jahr<\/strong><\/td>\n<td style=\"border-bottom: 2px solid #000;\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table>\n<tbody>\n<tr>\n<td><strong>1930<\/strong><\/td>\n<td>Gr\u00fcndung als Reparaturbetrieb von Gleichstrom- und Drehstrommotoren.<\/td>\n<\/tr>\n<tr>\n<td><strong>1945<\/strong><\/td>\n<td>Beginn der eigenen Motorenfertigung mit dem Bau von Drehstrom-Motoren.<\/td>\n<\/tr>\n<tr>\n<td><strong>1960 <\/strong><\/td>\n<td>Herstellung von Gleichstrommotoren.<\/td>\n<\/tr>\n<tr>\n<td><strong>1970<\/strong><\/td>\n<td>Fertigung einer neuen Produktserie: DC-Stromrichter mit Thyristoren f\u00fcr Hauptantriebe und Servomotoren.<\/td>\n<\/tr>\n<tr>\n<td><strong>1983<\/strong><\/td>\n<td>Produktionsbeginn von Scheibenl\u00e4ufermotoren.<\/td>\n<\/tr>\n<tr>\n<td><strong>1985 <\/strong><\/td>\n<td>Produktlinie wird mit Drehstrom-Servomotoren und Transistor-Stromrichtern erweitert.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Beginn der Aktivit\u00e4ten in Nord- und S\u00fcdamerika: Erste Niederlassung auf dem amerikanischen Kontinent 1987 in Hartford\/USA.<\/td>\n<\/tr>\n<tr>\n<td><strong>1991<\/strong><\/td>\n<td>Baum\u00fcller ist Pionier beim Einstieg in die Direktantriebstechnik.<\/td>\n<\/tr>\n<tr>\n<td><strong>1993<\/strong><\/td>\n<td>Programmierbares Steuerungs-System mega verbindet schnelle Regelungstechnik mit schneller Steuerung (SPS).<\/td>\n<\/tr>\n<tr>\n<td><strong>1995<\/strong><\/td>\n<td>Entwicklung und Produktion b\u00fcrstenloser, linearer Drehstromantriebe f\u00fcr schwere Lasten.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Baum\u00fcller macht den Antrieb intelligent.<\/td>\n<\/tr>\n<tr>\n<td><strong>1996<\/strong><\/td>\n<td>Erste Partnerschaft in Asien: Baum\u00fcller N\u00fcrnberg GmbH und KAT Controls Pvt. Ltd. India gr\u00fcnden das Gemeinschaftsunternehmen Baum\u00fcller-Kat India Pvt. Ltd.<\/td>\n<\/tr>\n<tr>\n<td><strong>1998<\/strong><\/td>\n<td>Einweihung der neuen Elektronikfertigung am Standort N\u00fcrnberg.<\/td>\n<\/tr>\n<tr>\n<td><strong>1999 <\/strong><\/td>\n<td>Ber\u00fchrungslose Linearmotoren mit kleinem Luftspalt f\u00fcr den Einsatz in F\u00f6rderanlagen.<\/td>\n<\/tr>\n<tr>\n<td><strong>2000<\/strong><\/td>\n<td>mega Drive Line II &#8211; weltweit schnellste SPS im Antrieb.<\/td>\n<\/tr>\n<tr>\n<td><strong>2001<\/strong><\/td>\n<td>Neue Regler- und Umrichtergeneration b maXX steht f\u00fcr Modularit\u00e4t, Skalierbarkeit und Offenheit.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Patenschaft mit Martin-Behaim-Gymnasium.<\/td>\n<\/tr>\n<tr>\n<td><strong>2002<\/strong><\/td>\n<td>Neue Synchronmotorenreihe DST erweitert Motorenpalette im Bereich der Direktantriebstechnik.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Motion Control-Konzept nach PLCopen reduziert die Komplexit\u00e4t von Automatisierungssoftware.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Projekt \u201eKunst in der Kantine\u201c.<\/td>\n<\/tr>\n<tr>\n<td><strong>2003 <\/strong><\/td>\n<td>Motion Control-Konzept wird von Single- auf Multi-Axis-Anwendungen erweitert, Projektierung von synchronen und gekoppelten Motion Control-Funktionalit\u00e4ten ist ohne Systemkenntnisse m\u00f6glich.<\/td>\n<\/tr>\n<tr>\n<td><strong>2004<\/strong><\/td>\n<td>Einweihung des neuen Schulungszentrums am Standort N\u00fcrnberg.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Feldbusl\u00f6sung auf Basis von Echtzeitethernet f\u00fcr Umrichterreihe b maXX 4400.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Im Zuge der Nachfolgeregelung tritt Andreas Baum\u00fcller als Gesch\u00e4ftsf\u00fchrer Technik in die Baum\u00fcller N\u00fcrnberg GmbH ein.<\/td>\n<\/tr>\n<tr>\n<td><strong>2005 <\/strong><\/td>\n<td>N\u00fcrmont Installations GmbH &amp; Co. KG wird in Baum\u00fcller integriert.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Erstmalige Verleihung des Studienpreises Mechatronik an der Friedrich-Alexander-Universit\u00e4t Erlangen.<\/td>\n<\/tr>\n<tr>\n<td><strong>2006<\/strong><\/td>\n<td>N\u00fcrmont Installations GmbH &amp; Co. KG befindet sich nach der \u00dcbernahme durch Baum\u00fcller auf Erfolgskurs und expandiert von Feucht nach USA und Asien.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Baum\u00fcller entwickelt Software sizemaXX zur Antriebsdimensionierung. Mit diesem Tool kann der Anwender bis zu sechs Antriebe dimensionieren.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Das Automatisierungs-Fachmagazin A&amp;D w\u00e4hlt sizemaXX auf den ersten Platz in der Rubrik Software &amp; Engineeringtools.<\/td>\n<\/tr>\n<tr>\n<td><strong>2007<\/strong><\/td>\n<td>Baum\u00fcller hat f\u00fcr die vektorgeregelte Ansteuerung von Standard-Normmotoren einen hocheffizienten und leicht bedienbaren Frequenzumrichter entwickelt \u2013 den b maXX 1000.<\/td>\n<\/tr>\n<tr>\n<td><strong>2008<\/strong><\/td>\n<td>Baum\u00fcller Sicherheitssteuerung b maXX-safePLC gewinnt den red dot design award.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Zuwachs in der Baum\u00fcller Unternehmensgruppe: Das 1996 gegr\u00fcndete Joint Venture Baum\u00fcller Kat India geht als Baum\u00fcller India zu 100 Prozent in die Baum\u00fcller Gruppe \u00fcber.<\/td>\n<\/tr>\n<tr>\n<td><strong>2009<\/strong><\/td>\n<td>Baum\u00fcller Anlagen-Systemtechnik GmbH &amp; Co. KG er\u00f6ffnet neuen Standort in Rossau.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>N\u00fcrmont Installation GmbH &amp; Co. KG er\u00f6ffnet Montagehalle am Standort Freiberg.<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td>Zertifizierung der b maXX-safePLC nach EN-13849.<\/td>\n<\/tr>\n<tr>\n<td><strong>2010<\/strong><\/td>\n<td>Hybridkonzept f\u00fcr mobile Antriebe in Nutzfahrzeugen im Projekt PowerMELA.<\/td>\n<\/tr>\n<tr>\n<td><strong>2011<\/strong><\/td>\n<td>DS-Motoren kommen erstmal zum Antrieb in Solar-Katamaranen zum Einsatz.<\/td>\n<\/tr>\n<tr>\n<td><strong>2012<\/strong><\/td>\n<td>Produktionsstart in Wujiang, China.<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h3>Quellenangabe:<\/h3>\n<table>\n<tbody>\n<tr bgcolor=\"#ffd6a0\">\n<td style=\"border-bottom: 2px solid #000; border-right: 1px solid #000;\"><strong>Unternehmen<\/strong><\/td>\n<td style=\"border-bottom: 2px solid #000;\"><\/td>\n<\/tr>\n<tr>\n<td><strong>Beschreibung<\/strong><\/td>\n<td>\u00a0https:\/\/de.wikipedia.org\/wiki\/Baum%C3%BCller<\/td>\n<\/tr>\n<tr>\n<td><strong>Historie<\/strong><\/td>\n<td>\u00a0http:\/\/www.baumueller.de\/gruppe_geschichte.htm<\/td>\n<\/tr>\n<tr>\n<td><\/td>\n<td><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Baum\u00fcller ist einer der weltweit f\u00fchrenden Hersteller von elektrischen Automatisierungs- und Antriebssystemen. Weltmarktf\u00fchrer Rang 486 Stand 2015 Zur\u00fcck zur Liste: Weltmarktf\u00fchrer Rang 401 \u2013 500 &nbsp; Das Unternehmen wurde 1930 gegr\u00fcndet und befindet sich nach wie vor in Familienbesitz. Der Stammsitz ist in N\u00fcrnberg. Heute ist die Baum\u00fcller Gruppe an \u00fcber 42 Standorten weltweit vertreten. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4618,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[56,30],"tags":[552,155,154,110],"class_list":["post-4538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nicht-boersennotiert","category-weltmarktfuehrer","tag-baumueller-nuernberg-gmbh","tag-geschichte","tag-historie","tag-meilensteine"],"_links":{"self":[{"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/posts\/4538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/comments?post=4538"}],"version-history":[{"count":11,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/posts\/4538\/revisions"}],"predecessor-version":[{"id":4651,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/posts\/4538\/revisions\/4651"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/media\/4618"}],"wp:attachment":[{"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/media?parent=4538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/categories?post=4538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.die-erfolgs-strategie.de\/aktien\/wp-json\/wp\/v2\/tags?post=4538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}